{"id":2,"date":"2022-06-07T16:25:07","date_gmt":"2022-06-07T16:25:07","guid":{"rendered":"https:\/\/flhomecare.wpengine.com\/microsite-template\/?page_id=2"},"modified":"2025-11-06T13:52:39","modified_gmt":"2025-11-06T13:52:39","slug":"home","status":"publish","type":"page","link":"https:\/\/www.firstlighthomecare.com\/home-healthcare-whittier\/","title":{"rendered":"Homepage"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.firstlighthomecare.com\/home-healthcare-whittier\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.firstlighthomecare.com\/home-healthcare-whittier\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.firstlighthomecare.com\/home-healthcare-whittier\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.firstlighthomecare.com\/home-healthcare-whittier\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.firstlighthomecare.com\/home-healthcare-whittier\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":0,"href":"https:\/\/www.firstlighthomecare.com\/home-healthcare-whittier\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.firstlighthomecare.com\/home-healthcare-whittier\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}